{"id":125269,"date":"2021-10-23T11:12:04","date_gmt":"2021-10-23T11:12:04","guid":{"rendered":"https:\/\/telegram-channel.net\/ar\/?post_type=telegram_channel&#038;p=125269"},"modified":"2021-10-23T11:12:05","modified_gmt":"2021-10-23T11:12:05","slug":"%d9%83%d9%88%d9%86%d9%8a-%f0%9f%92%8d%d8%ac%d9%86%d8%aa%d9%87%e2%9d%a4","status":"publish","type":"telegram_channel","link":"https:\/\/telegram-channel.net\/ar\/telegram-channel\/%d9%83%d9%88%d9%86%d9%8a-%f0%9f%92%8d%d8%ac%d9%86%d8%aa%d9%87%e2%9d%a4\/","title":{"rendered":"\u0643\u0648\u0646\u064a \ud83d\udc8d\u062c\u0646\u062a\u0647\u2764"},"content":{"rendered":"<p>\u0642\u0646\u0627\u0629 \u062a\u0647\u062a\u0645 \u0628\u0627\u0644\u062a\u062b\u0642\u064a\u0641 \u0627\u0644\u0639\u0627\u0645 \u0644\u0644\u062d\u064a\u0627\u0629 \u0627\u0644\u0632\u0648\u062c\u064a\u0629 \u0644\u0643\u0644 \u0645\u0646 \u0627\u0644\u0645\u0642\u0628\u0644\u0627\u062a \u0639\u0644\u0649 \u0627\u0644\u0632\u0648\u0627\u062c \u0648\u0627\u0644\u0645\u062a\u0632\u0648\u062c\u0627\u062a \u0648\u0627\u0644\u062a\u064a \u0644\u0645 \u062a\u062a\u0632\u0648\u062c \u0628\u0639\u062f<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0642\u0646\u0627\u0629 \u062a\u0647\u062a\u0645 \u0628\u0627\u0644\u062a\u062b\u0642\u064a\u0641 \u0627\u0644\u0639\u0627\u0645 \u0644\u0644\u062d\u064a\u0627\u0629 \u0627\u0644\u0632\u0648\u062c\u064a\u0629 \u0644\u0643\u0644 \u0645\u0646 \u0627\u0644\u0645\u0642\u0628\u0644\u0627\u062a \u0639\u0644\u0649 \u0627\u0644\u0632\u0648\u0627\u062c \u0648\u0627\u0644\u0645\u062a\u0632\u0648\u062c\u0627\u062a \u0648\u0627\u0644\u062a\u064a \u0644\u0645 \u062a\u062a\u0632\u0648\u062c \u0628\u0639\u062f<\/p>\n","protected":false},"author":56,"featured_media":125270,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-125269","telegram_channel","type-telegram_channel","status-publish","has-post-thumbnail","hentry","country-iraq","telegram_channel_category-family-children"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/telegram-channel.net\/ar\/wp-json\/wp\/v2\/telegram_channel\/125269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/telegram-channel.net\/ar\/wp-json\/wp\/v2\/telegram_channel"}],"about":[{"href":"https:\/\/telegram-channel.net\/ar\/wp-json\/wp\/v2\/types\/telegram_channel"}],"author":[{"embeddable":true,"href":"https:\/\/telegram-channel.net\/ar\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/telegram-channel.net\/ar\/wp-json\/wp\/v2\/comments?post=125269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/telegram-channel.net\/ar\/wp-json\/wp\/v2\/media\/125270"}],"wp:attachment":[{"href":"https:\/\/telegram-channel.net\/ar\/wp-json\/wp\/v2\/media?parent=125269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}