{"id":124736,"date":"2021-08-23T23:54:04","date_gmt":"2021-08-23T23:54:04","guid":{"rendered":"https:\/\/telegram-channel.net\/pt\/?post_type=telegram_channel&#038;p=124736"},"modified":"2021-08-23T23:54:04","modified_gmt":"2021-08-23T23:54:04","slug":"joao-claudio-rufino-biblia-play-%f0%9f%99%8f","status":"publish","type":"telegram_channel","link":"https:\/\/telegram-channel.net\/pt\/telegram-channel\/joao-claudio-rufino-biblia-play-%f0%9f%99%8f\/","title":{"rendered":"Jo\u00e3o Claudio Rufino &#8211; B\u00edblia Play \ud83d\ude4f"},"content":{"rendered":"<p>Conte\u00fados exclusivos do Universo B\u00edblico e Teol\u00f3gico do Prof. Jo\u00e3o Claudio Rufino<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conte\u00fados exclusivos do Universo B\u00edblico e Teol\u00f3gico do Prof. Jo\u00e3o Claudio Rufino<\/p>\n","protected":false},"author":56,"featured_media":124737,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-124736","telegram_channel","type-telegram_channel","status-publish","has-post-thumbnail","hentry","telegram_channel_category-religion"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/telegram_channel\/124736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/telegram_channel"}],"about":[{"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/types\/telegram_channel"}],"author":[{"embeddable":true,"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/comments?post=124736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/media\/124737"}],"wp:attachment":[{"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/media?parent=124736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}