{"id":127406,"date":"2022-10-11T08:53:20","date_gmt":"2022-10-11T08:53:20","guid":{"rendered":"https:\/\/telegram-channel.net\/pt\/?post_type=telegram_channel&#038;p=127406"},"modified":"2022-10-11T08:53:20","modified_gmt":"2022-10-11T08:53:20","slug":"apps-for-smart-tvs-tv-boxes-tv-sticks-and-android-devices-%f0%9f%93%b1%f0%9f%92%bb%f0%9f%93%ba","status":"publish","type":"telegram_channel","link":"https:\/\/telegram-channel.net\/pt\/telegram-channel\/apps-for-smart-tvs-tv-boxes-tv-sticks-and-android-devices-%f0%9f%93%b1%f0%9f%92%bb%f0%9f%93%ba\/","title":{"rendered":"Apps for smart TVs, TV boxes, TV sticks and Android devices! \ud83d\udcf1\ud83d\udcbb\ud83d\udcfa"},"content":{"rendered":"<p>YouCine &#8211; Um Melhor APP De S\u00e9ries e Filmes Que Voc\u00ea Vai Adora <\/p>\n<p>Gr\u00e1tis, Nenhum An\u00fancio, Grande Recursos de Filmes, S\u00e9ries e Premier League para Assistir! <\/p>\n<p>Youcine (Atualizado) \u00e9 um aplicativo de filmes, s\u00e9ries e animes em HD e Full HD e que voc\u00ea encontrar\u00e1 na internet. Para aqueles que optam por se divertir com filmes e series, os requisitos que est\u00e3o sempre no topo ser\u00e3o a diversidade e a reprodu\u00e7\u00e3o suave. Ent\u00e3o, escolha o YouCine, ele ser\u00e1 o seu companheiro legal para assistir filmes e s\u00e9ries gratuitos! <\/p>\n<p>\u2022Sobre o YouCine Apk<\/p>\n<p>\u2022Filmes e s\u00e9ries mais populares no YouCine<\/p>\n<p>\u2022Futebol ao Vivo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>YouCine &#8211; Um Melhor APP De S\u00e9ries e Filmes Que Voc\u00ea Vai Adora Gr\u00e1tis, Nenhum An\u00fancio, Grande Recursos de Filmes, S\u00e9ries e Premier League para Assistir! Youcine (Atualizado) \u00e9 um&#8230;<\/p>\n","protected":false},"author":697,"featured_media":127407,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-127406","telegram_channel","type-telegram_channel","status-publish","has-post-thumbnail","hentry","telegram_channel_category-movies"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/telegram_channel\/127406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/telegram_channel"}],"about":[{"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/types\/telegram_channel"}],"author":[{"embeddable":true,"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/users\/697"}],"replies":[{"embeddable":true,"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/comments?post=127406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/media\/127407"}],"wp:attachment":[{"href":"https:\/\/telegram-channel.net\/pt\/wp-json\/wp\/v2\/media?parent=127406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}